{"id":427,"date":"2022-09-29T09:32:16","date_gmt":"2022-09-29T09:32:16","guid":{"rendered":"https:\/\/www.leirivolt.pt\/contacts\/"},"modified":"2023-02-08T15:08:19","modified_gmt":"2023-02-08T15:08:19","slug":"contacts","status":"publish","type":"page","link":"https:\/\/www.leirivolt.pt\/en\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"<section id=\"contactos-block\" class=\"mt-0 full-width\">\n<div class=\"row\">\n<div class=\"col-lg-6\"><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d10316.032937683847!2d-8.86872531769243!3d39.762671008581336!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd220ce77597368b%3A0xfffb280cb4d75eae!2sLeirivolt%2C%20Lda!5e0!3m2!1spt-PT!2spt!4v1665673042541!5m2!1spt-PT!2spt\" width=\"100%\" height=\"540\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n<div class=\"col-lg-6\">\n<div class=\"container\">\n<div>\n<h5>Address<\/h5>\n<ul class=\"contact-list\">\n<li class=\"address\">Rua Vale da Arieira, Lt 4<br \/>\nBarosa &#8211; 2400-491 Leiria,<br \/>\nPortugal<\/li>\n<li class=\"gps\">N39\u00ba 45.488&#8242; &#8211; W08\u00ba 51.568&#8242;<\/li>\n<\/ul>\n<\/div>\n<div>\n<h5>Contacts<\/h5>\n<ul class=\"contact-list\">\n<li class=\"email\"><a href=\"mailto:geral@leirivolt.pt\">geral@leirivolt.pt<\/a><\/li>\n<li class=\"phone\">+351 244 838 703<small><br \/>\n(Call to the national landline network)<\/small><\/li>\n<li class=\"fax\">+351 244 838 705<\/li>\n<\/ul>\n<\/div>\n<div>\n<h5>Follow us<\/h5>\n<ul class=\"social-list\">\n<li class=\"facebook\"><a href=\"https:\/\/www.facebook.com\/leirivolt\/\">facebook\/leirivolt<\/a><\/li>\n<li class=\"instagram\"><a href=\"https:\/\/www.instagram.com\/leirivolt\/\">instagram\/leirivolt<\/a><\/li>\n<li class=\"linkedin\"><a href=\"https:\/\/www.linkedin.com\/company\/leirivolt-lda\/\">linkedin\/leirivolt-lda<\/a><\/li>\n<li class=\"youtube\"><a href=\"https:\/\/www.youtube.com\/channel\/UCa3j2lrLVVRdtDgCdJRt6Sw?app=desktop\">youtube\/leirivolt<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"contact-form-block\">\n<div class=\"row\">\n<div class=\"col-lg-6\">\n<h2>Message<\/h2>\n<\/div>\n<div class=\"col-lg-6\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2911-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2911\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/427#wpcf7-f2911-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2911\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2911-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"content\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-6 col-lg-4\">\n\t\t\t<p><label>Name*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-6 col-lg-4\">\n\t\t\t<p><label>Contact*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-499\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-499\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-lg-4\">\n\t\t\t<p><label>E-mail*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col\">\n\t\t\t<p><label>Message<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row submit-row\">\n\t\t<div class=\"col-xxl-auto\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-335\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-335\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><span>I have read and agree with the <a href=\"https:\/\/www.leirivolt.pt\/politica-privacidade\">Privacy Policy<\/a>.<\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-2\">\n\t\t\t\t<p><input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"1395301299\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/wpcf7_captcha\/1395301299.png\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-md-2\">\n\t\t\t\t<p><label>CAPTCHA*<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-xxl-auto submit-block\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Address Rua Vale da Arieira, Lt 4 Barosa &#8211; 2400-491 Leiria, Portugal N39\u00ba 45.488&#8242; &#8211; W08\u00ba 51.568&#8242; Contacts geral@leirivolt.pt +351 244 838 703 (Call to the national landline network) +351 244 838 705 Follow us facebook\/leirivolt instagram\/leirivolt linkedin\/leirivolt-lda youtube\/leirivolt Message<\/p>\n","protected":false},"author":1,"featured_media":412,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-427","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacts | Renewable Energy Company | Leirivolt<\/title>\n<meta name=\"description\" content=\"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leirivolt.pt\/en\/contacts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacts | Renewable Energy Company | Leirivolt\" \/>\n<meta property=\"og:description\" content=\"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leirivolt.pt\/en\/contacts\/\" \/>\n<meta property=\"og:site_name\" content=\"Leirivolt, Lda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leirivolt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T15:08:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/11\/contacts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1627\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/\",\"name\":\"Contacts | Renewable Energy Company | Leirivolt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contacts.jpg\",\"datePublished\":\"2022-09-29T09:32:16+00:00\",\"dateModified\":\"2023-02-08T15:08:19+00:00\",\"description\":\"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contacts.jpg\",\"contentUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/contacts.jpg\",\"width\":1627,\"height\":393},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/contacts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\",\"name\":\"Leirivolt, Lda\",\"description\":\"Solu\u00e7\u00f5es de Energia desde 2004\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#organization\",\"name\":\"Leirivolt, Lda\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_leirivolt.svg\",\"contentUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_leirivolt.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Leirivolt, Lda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leirivolt\\\/\",\"https:\\\/\\\/www.instagram.com\\\/leirivolt\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/leirivolt-lda\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCa3j2lrLVVRdtDgCdJRt6Sw?app=desktop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacts | Renewable Energy Company | Leirivolt","description":"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leirivolt.pt\/en\/contacts\/","og_locale":"en_US","og_type":"article","og_title":"Contacts | Renewable Energy Company | Leirivolt","og_description":"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.","og_url":"https:\/\/www.leirivolt.pt\/en\/contacts\/","og_site_name":"Leirivolt, Lda","article_publisher":"https:\/\/www.facebook.com\/leirivolt\/","article_modified_time":"2023-02-08T15:08:19+00:00","og_image":[{"width":1627,"height":393,"url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/11\/contacts.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/","url":"https:\/\/www.leirivolt.pt\/en\/contacts\/","name":"Contacts | Renewable Energy Company | Leirivolt","isPartOf":{"@id":"https:\/\/www.leirivolt.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/#primaryimage"},"image":{"@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/11\/contacts.jpg","datePublished":"2022-09-29T09:32:16+00:00","dateModified":"2023-02-08T15:08:19+00:00","description":"Leirivolt Contact. For any question about electrical installations, electrical panels, photovoltaic, electric mobility.","breadcrumb":{"@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leirivolt.pt\/en\/contacts\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/#primaryimage","url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/11\/contacts.jpg","contentUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/11\/contacts.jpg","width":1627,"height":393},{"@type":"BreadcrumbList","@id":"https:\/\/www.leirivolt.pt\/en\/contacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.leirivolt.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Contacts"}]},{"@type":"WebSite","@id":"https:\/\/www.leirivolt.pt\/en\/#website","url":"https:\/\/www.leirivolt.pt\/en\/","name":"Leirivolt, Lda","description":"Solu\u00e7\u00f5es de Energia desde 2004","publisher":{"@id":"https:\/\/www.leirivolt.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leirivolt.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leirivolt.pt\/en\/#organization","name":"Leirivolt, Lda","url":"https:\/\/www.leirivolt.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leirivolt.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/09\/logo_leirivolt.svg","contentUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/09\/logo_leirivolt.svg","width":"1024","height":"1024","caption":"Leirivolt, Lda"},"image":{"@id":"https:\/\/www.leirivolt.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leirivolt\/","https:\/\/www.instagram.com\/leirivolt\/","https:\/\/www.linkedin.com\/company\/leirivolt-lda\/","https:\/\/www.youtube.com\/channel\/UCa3j2lrLVVRdtDgCdJRt6Sw?app=desktop"]}]}},"_links":{"self":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/pages\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":2,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/pages\/427\/revisions"}],"predecessor-version":[{"id":3218,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/pages\/427\/revisions\/3218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/media\/412"}],"wp:attachment":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/media?parent=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}