{"id":3026,"date":"2022-12-17T10:20:39","date_gmt":"2022-12-17T10:20:39","guid":{"rendered":"https:\/\/www.leirivolt.pt\/projeto\/power-panel\/"},"modified":"2022-12-17T10:20:39","modified_gmt":"2022-12-17T10:20:39","slug":"power-panel","status":"publish","type":"projeto","link":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/","title":{"rendered":"Power Panel"},"content":{"rendered":"<div class=\"owl-carousel\">\n<div class=\"item\" data-hash=\"01\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1877 size-full\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"2082\" srcset=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg 2560w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-300x244.jpg 300w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-1024x833.jpg 1024w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-768x625.jpg 768w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-1536x1249.jpg 1536w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-2048x1666.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<div class=\"item\" data-hash=\"02\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1879 size-full\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"2040\" srcset=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-scaled.jpg 2560w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-300x239.jpg 300w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-1024x816.jpg 1024w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-768x612.jpg 768w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-1536x1224.jpg 1536w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-2048x1632.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<div class=\"item\" data-hash=\"03\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1875 size-full\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" srcset=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-scaled.jpg 2560w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-300x200.jpg 300w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-1024x683.jpg 1024w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-768x512.jpg 768w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-1536x1024.jpg 1536w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<div class=\"item\" data-hash=\"04\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1883 size-full\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-scaled.jpg 2560w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-300x200.jpg 300w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-1024x683.jpg 1024w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-768x512.jpg 768w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-1536x1024.jpg 1536w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n<div class=\"item\" data-hash=\"05\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1881 size-full\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" srcset=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-scaled.jpg 1707w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-200x300.jpg 200w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-683x1024.jpg 683w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-768x1152.jpg 768w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-1024x1536.jpg 1024w, https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-1365x2048.jpg 1365w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><\/div>\n<\/div>\n<ul class=\"owl-hash-nav\">\n<li><a href=\"#01\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-858\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg\" alt=\"\" width=\"900\" height=\"920\"><\/a><\/li>\n<li><a href=\"#02\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-862\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6268_01-scaled.jpg\" alt=\"\" width=\"960\" height=\"1280\"><\/a><\/li>\n<li><a href=\"#03\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-858\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6251_-scaled.jpg\" alt=\"\" width=\"900\" height=\"920\"><\/a><\/li>\n<li><a href=\"#04\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-862\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6250-scaled.jpg\" alt=\"\" width=\"960\" height=\"1280\"><\/a><\/li>\n<li><a href=\"#05\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-862\" src=\"http:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6278-scaled.jpg\" alt=\"\" width=\"960\" height=\"1280\"><\/a><\/li>\n<\/ul>\n<p>Power Panel<br \/>\nFootwear Industry in Leiria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Power Panel Footwear Industry in Leiria.<\/p>\n","protected":false},"featured_media":1878,"template":"","categories":[87,96],"class_list":["post-3026","projeto","type-projeto","status-publish","has-post-thumbnail","hentry","category-electrical-switchboards","category-distribution"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Power Panel - Leirivolt, Lda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Power Panel - Leirivolt, Lda\" \/>\n<meta property=\"og:description\" content=\"Power Panel Footwear Industry in Leiria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/\" \/>\n<meta property=\"og:site_name\" content=\"Leirivolt, Lda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leirivolt\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2082\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/\",\"name\":\"Power Panel - Leirivolt, Lda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_6264_01-scaled.jpg\",\"datePublished\":\"2022-12-17T10:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_6264_01-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_6264_01-scaled.jpg\",\"width\":2560,\"height\":2082},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/projeto\\\/power-panel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Power Panel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\",\"name\":\"Leirivolt, Lda\",\"description\":\"Solu\u00e7\u00f5es de Energia desde 2004\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#organization\",\"name\":\"Leirivolt, Lda\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_leirivolt.svg\",\"contentUrl\":\"https:\\\/\\\/www.leirivolt.pt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_leirivolt.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Leirivolt, Lda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.leirivolt.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leirivolt\\\/\",\"https:\\\/\\\/www.instagram.com\\\/leirivolt\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/leirivolt-lda\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCa3j2lrLVVRdtDgCdJRt6Sw?app=desktop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Power Panel - Leirivolt, Lda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/","og_locale":"en_US","og_type":"article","og_title":"Power Panel - Leirivolt, Lda","og_description":"Power Panel Footwear Industry in Leiria.","og_url":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/","og_site_name":"Leirivolt, Lda","article_publisher":"https:\/\/www.facebook.com\/leirivolt\/","og_image":[{"width":2560,"height":2082,"url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/","url":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/","name":"Power Panel - Leirivolt, Lda","isPartOf":{"@id":"https:\/\/www.leirivolt.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/#primaryimage"},"image":{"@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg","datePublished":"2022-12-17T10:20:39+00:00","breadcrumb":{"@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/#primaryimage","url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg","contentUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2023\/01\/IMG_6264_01-scaled.jpg","width":2560,"height":2082},{"@type":"BreadcrumbList","@id":"https:\/\/www.leirivolt.pt\/en\/projeto\/power-panel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.leirivolt.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Power Panel"}]},{"@type":"WebSite","@id":"https:\/\/www.leirivolt.pt\/en\/#website","url":"https:\/\/www.leirivolt.pt\/en\/","name":"Leirivolt, Lda","description":"Solu\u00e7\u00f5es de Energia desde 2004","publisher":{"@id":"https:\/\/www.leirivolt.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leirivolt.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leirivolt.pt\/en\/#organization","name":"Leirivolt, Lda","url":"https:\/\/www.leirivolt.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leirivolt.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/09\/logo_leirivolt.svg","contentUrl":"https:\/\/www.leirivolt.pt\/wp-content\/uploads\/2022\/09\/logo_leirivolt.svg","width":"1024","height":"1024","caption":"Leirivolt, Lda"},"image":{"@id":"https:\/\/www.leirivolt.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leirivolt\/","https:\/\/www.instagram.com\/leirivolt\/","https:\/\/www.linkedin.com\/company\/leirivolt-lda\/","https:\/\/www.youtube.com\/channel\/UCa3j2lrLVVRdtDgCdJRt6Sw?app=desktop"]}]}},"_links":{"self":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/projeto\/3026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/projeto"}],"about":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/types\/projeto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/media\/1878"}],"wp:attachment":[{"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/media?parent=3026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leirivolt.pt\/en\/wp-json\/wp\/v2\/categories?post=3026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}